{"id":13537,"date":"2021-09-13T15:00:41","date_gmt":"2021-09-13T13:00:41","guid":{"rendered":"https:\/\/svhuesten09.de\/web\/?p=13537"},"modified":"2021-09-13T15:00:41","modified_gmt":"2021-09-13T13:00:41","slug":"02-huesten-verliert-nicht-nur-das-spiel-sondern-auch-seinen-kapitaen","status":"publish","type":"post","link":"https:\/\/svhuesten09.de\/web\/2021\/09\/13\/02-huesten-verliert-nicht-nur-das-spiel-sondern-auch-seinen-kapitaen\/","title":{"rendered":"0:2 &#8211; H\u00fcsten verliert nicht nur das Spiel, sondern auch seinen Kapit\u00e4n"},"content":{"rendered":"<p>Der TuS Langenholthausen ist beim SV H\u00fcsten 09 in die Erfolgsspur zur\u00fcckgekehrt und hat das HSK-Derby erwartungsgem\u00e4\u00df mit 2:0 gewonnen.<\/p>\n<p>Eine Woche nach der 2:3-Niederlage gegen die SpVgg Olpe, bei der der TuS eine 2:0-F\u00fchrung noch aus der Hand gegeben hatte, tat sich Langenholthausen \u00fcber weite Strecken schwer, eine L\u00f6sung gegen diszipliniert auftretende H\u00fcstener zu finden. Nur selten gelang es der Mannschaft von TuS-Coach Uli Mayer, das H\u00fcstener Tor ernsthaft in Gefahr zu bringen, w\u00e4hrend die 09er ihre Konterm\u00f6glichkeiten zu unsauber ausspielten.<\/p>\n<p>Nach dem Seitenwechsel machte aber die individuelle Klasse der G\u00e4ste den Unterschied. Lukas Kessler sorgte nach einer Stunde f\u00fcr die durchaus verdiente F\u00fchrung der D\u00fcsterloh-Kicker (60.), die diese in der Folge auch nicht mehr aus der Hand gaben und mit dem 2:0 von Gian-Marco De Luca in der Schlussphase den Sack zumachten. H\u00fcsten musste nach Abpfiff nicht nur die zweite Niederlage im dritten Spiel verdauen, sondern auch den Verlust von Kapit\u00e4n Patrick Kampschulte, der wegen einer Notbremse in der 85. Minute noch die rote Karte sah und damit in den kommenden Spielen fehlen wird.<\/p>\n<p>\u201eWir haben uns wieder um den Lohn unserer Arbeit gebracht. Mir w\u00e4re es lieber gewesen, dass uns der Gegner geschlagen h\u00e4tte statt wir uns selbst. Bei den Gegentoren stellen wir uns einfach nicht clever genug an und treffen bei Gegenst\u00f6\u00dfen viel zu h\u00e4ufig die falschen Entscheidungen. Ma\u00dflos \u00e4rgert mich allerdings die rote Karte, die einfach maximal \u00fcberfl\u00fcssig ist\u201c, fand 09-Trainer J\u00f6rg Fischer deutliche Worte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der TuS Langenholthausen ist beim SV H\u00fcsten 09 in die Erfolgsspur zur\u00fcckgekehrt und hat das HSK-Derby erwartungsgem\u00e4\u00df mit 2:0 gewonnen. Eine Woche nach der 2:3-Niederlage gegen die SpVgg Olpe, bei der der TuS eine 2:0-F\u00fchrung noch aus der Hand gegeben hatte, tat sich Langenholthausen \u00fcber weite Strecken schwer, eine L\u00f6sung gegen diszipliniert auftretende H\u00fcstener zu [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":13538,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32,1],"tags":[],"_links":{"self":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13537"}],"collection":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/comments?post=13537"}],"version-history":[{"count":1,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13537\/revisions"}],"predecessor-version":[{"id":13539,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13537\/revisions\/13539"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media\/13538"}],"wp:attachment":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media?parent=13537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/categories?post=13537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/tags?post=13537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}