{"id":13593,"date":"2021-10-22T10:00:42","date_gmt":"2021-10-22T08:00:42","guid":{"rendered":"https:\/\/svhuesten09.de\/web\/?p=13593"},"modified":"2021-10-20T17:49:38","modified_gmt":"2021-10-20T15:49:38","slug":"09-wochenende-im-schnelldurchlauf-63","status":"publish","type":"post","link":"https:\/\/svhuesten09.de\/web\/2021\/10\/22\/09-wochenende-im-schnelldurchlauf-63\/","title":{"rendered":"09-Wochenende im Schnelldurchlauf"},"content":{"rendered":"<p>Zum Start ins Wochenende freut sich die Altherren-Mannschaft des SV H\u00fcsten 09 auf ihr Kreispokalspiel beim TuS Niedereimer am Freitag, den 22. Oktober, um 19:30 Uhr. Die Jungs, auf die bei der Organisation der Heimspiele der ersten Mannschaft des SV H\u00fcsten 09 immer Verlass ist, ben\u00f6tigen jede Unterst\u00fctzung, um im Pokal eine Runde weiterzukommen. Die Mannschaft w\u00fcrde sich freuen.<\/p>\n<p>Am Samstag, den 23. Oktober, enden die Herbstferien in Nordrhein-Westfalen und damit ist das Heimprogramm der 09-Mannschaften \u00fcberschaubar. Daf\u00fcr richtet die Jugendabteilung SV H\u00fcsten 09 den McDonald&#8217;s Cup aus. Derweil finden mit Beteiligung des JLZ Neheim-H\u00fcsten keine Spiele statt.<\/p>\n<p>Die zweite Seniorenmannschaft des SV H\u00fcsten 09 gastiert am Sonntag, den 24. Oktober, bei der SG Herdringen\/M\u00fcschede um 15:00 Uhr am Telgenweg. Die Jungs m\u00fcssen endlich mal wieder die 09-Fans \u00fcberzeugen. Auch die Landesligamannschaft, die ihr Ausw\u00e4rtsspiel am vergangenen Wochenende bei der SpVgg Olpe denkbar knapp mit 0:1 verlor, hat spielfrei und konzentriert sich auf ihr n\u00e4chstes Heimspiel gegen RW L\u00fcdenscheid am Sonntag, den 31. Oktober, um 15:00 Uhr. Der Fokus des H\u00fcstener Aush\u00e4ngeschildes sollte auf dieser Partie liegen.<\/p>\n<p>Somit bestreitet nur die dritte Mannschaft der 09er am vierten Oktober-Wochenende noch ihr Heimspiel gegen TuRa Freienohl II, das am Sonntag um 13:00 Uhr auf dem Kunstrasenplatz in H\u00fcsten angepfiffen wird. Jungs, haut rein! Alles f\u00fcr 09!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zum Start ins Wochenende freut sich die Altherren-Mannschaft des SV H\u00fcsten 09 auf ihr Kreispokalspiel beim TuS Niedereimer am Freitag, den 22. Oktober, um 19:30 Uhr. Die Jungs, auf die bei der Organisation der Heimspiele der ersten Mannschaft des SV H\u00fcsten 09 immer Verlass ist, ben\u00f6tigen jede Unterst\u00fctzung, um im Pokal eine Runde weiterzukommen. Die [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":13594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32,1,58],"tags":[],"_links":{"self":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13593"}],"collection":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/comments?post=13593"}],"version-history":[{"count":1,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13593\/revisions"}],"predecessor-version":[{"id":13595,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/13593\/revisions\/13595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media\/13594"}],"wp:attachment":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media?parent=13593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/categories?post=13593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/tags?post=13593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}