{"id":14735,"date":"2023-10-07T11:52:24","date_gmt":"2023-10-07T09:52:24","guid":{"rendered":"https:\/\/svhuesten09.de\/web\/?p=14735"},"modified":"2023-10-07T11:52:24","modified_gmt":"2023-10-07T09:52:24","slug":"09-wochenende-im-schnelldurchlauf-124","status":"publish","type":"post","link":"https:\/\/svhuesten09.de\/web\/2023\/10\/07\/09-wochenende-im-schnelldurchlauf-124\/","title":{"rendered":"09-Wochenende im Schnelldurchlauf"},"content":{"rendered":"<p>Auch am zweiten Oktober-Wochenende sind die drei Seniorenmannschaften des SV H\u00fcsten 09 wieder im Einsatz.<\/p>\n<p>Bereits am Samstag, den 07. Oktober, spielt die zweite Mannschaft beim TuS Rumbeck. Nach der \u00e4rgerlichen 1:3-Heimniederlage gegen Tabellenf\u00fchrer SSV K\u00fcntrop sind die Gr\u00fcn-Wei\u00dfen nun beim Tabellenvorletzten zu Gast und wollen dort den vierten Saisonsieg einfahren. &#8222;F\u00fcr beide Mannschaften ist das nat\u00fcrlich ein sehr wichtiges Spiel, denn auch Rumbeck ist nicht gut aus den Startl\u00f6chern gekommen. Allerdings muss es unser Anspruch mit der vorhandenen Qualit\u00e4t im Kader sein, mit dem Kampf um den Klassenerhalt nichts zu tun zu haben. Daher fahren wir mit der klaren Zielsetzung nach Rumbeck, dort einen Dreier einzufahren, wenngleich wir auch mit dem n\u00f6tigen Respekt dort antreten werden&#8220;, k\u00fcndigt Trainer Ufuk \u00dczel an.<\/p>\n<p>Weiter geht es dann am Sonntag, den 08. Oktober, um 13:00 Uhr mit der Partie der H\u00fcstener D-Liga-Mannschaft gegen die SG Allendorf\/Amecke III. In der Vorwoche konnten die 09er die Partie beim SV Bachum\/Bergheim III mit 4:3 f\u00fcr sich entscheiden und sind damit aktuell Tabellenzweiter der Kreisliga D Arnsberg.<\/p>\n<p>Nachlegen m\u00f6chte unbedingt das Bezirksligateam des SV H\u00fcsten 09, das am Sonntag, den 08. Oktober, um 15:00 Uhr beim ehemaligen Landesligagef\u00e4hrten VfL Bad Berleburg antritt. Die Badest\u00e4dter haben aus den vergangenen vier Partien zehn Punkte geholt und zuletzt dem Tabellenf\u00fchrer SF H\u00fcingsen ein 0:0 abgetrotzt. Trotzdem wollen die H\u00fcstener in Bad Berleburg dreifach punkten und nach dem 4:0-Erfolg gegen die SG Serkenrode\/Fretter nachlegen. &#8222;Uns steht ein unangenehmes Ausw\u00e4rtsspiel bevor, zumal sich der VfL Bad Berleburg in den vergangenen Wochen deutlich stabilisiert und aus den vergangenen vier Partien zehn Punkte geholt hat. Wir wollen aber unsere Leistung aus der Vorwoche best\u00e4tigen und erstmalig zwei Siege in Folge einfahren&#8220;, sagt Trainer Jan H\u00fcttemann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auch am zweiten Oktober-Wochenende sind die drei Seniorenmannschaften des SV H\u00fcsten 09 wieder im Einsatz. Bereits am Samstag, den 07. Oktober, spielt die zweite Mannschaft beim TuS Rumbeck. Nach der \u00e4rgerlichen 1:3-Heimniederlage gegen Tabellenf\u00fchrer SSV K\u00fcntrop sind die Gr\u00fcn-Wei\u00dfen nun beim Tabellenvorletzten zu Gast und wollen dort den vierten Saisonsieg einfahren. &#8222;F\u00fcr beide Mannschaften ist [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":14659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32,33,34,1],"tags":[],"_links":{"self":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/14735"}],"collection":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/comments?post=14735"}],"version-history":[{"count":1,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/14735\/revisions"}],"predecessor-version":[{"id":14736,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/posts\/14735\/revisions\/14736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media\/14659"}],"wp:attachment":[{"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/media?parent=14735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/categories?post=14735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svhuesten09.de\/web\/wp-json\/wp\/v2\/tags?post=14735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}